{"id":64887,"date":"2026-03-13T09:30:20","date_gmt":"2026-03-13T08:30:20","guid":{"rendered":"https:\/\/dam-online.de\/veranstaltung\/mittelklassig-modernisiert-kuenstlerinnengespraech-mit-karla-zipfel\/"},"modified":"2026-05-05T10:07:30","modified_gmt":"2026-05-05T08:07:30","slug":"mittelklassig-modernisiert-kuenstlerinnengespraech-mit-karla-zipfel","status":"publish","type":"tribe_events","link":"https:\/\/dam-online.de\/en\/veranstaltung\/mittelklassig-modernisiert-kuenstlerinnengespraech-mit-karla-zipfel\/","title":{"rendered":"Mittelklassig modernisiert &#8211; K\u00fcnstlerinnengespr\u00e4ch mit Karla Zipfel"},"content":{"rendered":"<h2>Mittelklassig modernisiert &#8211; K\u00fcnstlerinnengespr\u00e4ch mit Karla Zipfel<\/h2>\n<p><strong>07. Mai 2026, 19 Uhr <\/strong><br \/>\n<b>DAM Auditorium<br \/>\nTeilnahme kostenlos<\/b><\/p>\n<p><strong>Teilnahme per Zoom: <a href=\"https:\/\/uni-bremen.zoom-x.de\/j\/68783135308?pwd=bxFiYC9falHKZqqoTRwNznUaAFptfv.1\">Zoom-Link\u00a0<\/a><\/strong><\/p>\n<p>Karla Zipfel n\u00e4hert sich als K\u00fcnstlerin in Form von Skulptur, Installation und Socialmedia den Themen Wohnen, Wohnraumgestaltung und den damit verbundenen gesellschaftlichen Versprechen. In einem K\u00fcnstlerinnengespr\u00e4ch stellt sie Arbeiten der letzten Jahre vor. Dabei geht es um kollektive und individuelle Gestaltungsmuster von Einfamilienh\u00e4usern, das Narrativ des Bausparfuchses, die emotionale Qualit\u00e4t verschiedener Heizarten und die kreative Ansprache potentieller Vermieter:innen. In Kurzvideos auf Instagram und Tiktok (<a href=\"https:\/\/www.instagram.com\/karlazipfel\/reels\/\">@karlazipfel)<\/a> r\u00fcckt sie Geb\u00e4ude und Orte au\u00dferhalb des Architekturkanons in den Fokus, wie Sparkassen-Filialen und Zweckbauten der 80er und 90er, die Kleinst\u00e4dte und Vororte pr\u00e4gen.<\/p>\n<p>Karla Zipfel ist 1993 geboren, aufgewachsen in der s\u00fcdbadischen Kleinstadt Bad Krozingen und lebt in Berlin. Sie studierte Bildende K\u00fcnste an der HFBK Hamburg. Ihre Arbeiten wurden u.a. gezeigt von: Deichtorhallen Hamburg, Kunsthalle Basel, Kunsthalle Recklinghausen, Kunstverein Freiburg.<\/p>\n<p>Der Vortrag geho\u0308rt zum Programm des Forschungsfeldes <em>wohnen+\/\u2013ausstellen<\/em> in der Kooperation des Instituts fu\u0308r Kunstwissenschaft \u2013 Filmwissenschaft \u2013 Kunstpa\u0308dagogik der Universita\u0308t Bremen mit dem Mariann Steegmann Institut. Kunst &amp; Gender (Leitung: Kathrin Heinz).<\/p>\n<p>Weitere Informationen sowie der Zoomlink zur Veranstaltung finden sich unter: <a href=\"http:\/\/www.mariann-steegmann-institut.de\/\">http:\/\/www.mariann-steegmann-institut.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Karla Zipfel n\u00e4hert sich als K\u00fcnstlerin in Form von Skulptur, Installation und Socialmedia den Themen Wohnen, Wohnraumgestaltung und den damit verbundenen gesellschaftlichen Versprechen. In einem K\u00fcnstlerinnengespr\u00e4ch stellt sie Arbeiten der letzten Jahre vor.<\/p>\n","protected":false},"author":7,"featured_media":64882,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[622,233],"veranstaltungs_formate":[132,500],"tribe_events_cat":[253],"hf_cat_tribe_events":[],"class_list":["post-64887","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-begleitprogramm-suburbia","tag-mega-menu-en","veranstaltungs_formate-begleitprogramm","veranstaltungs_formate-expertengespraech","veranstaltungs_bedingungen-im-haus","tribe_events_cat-veranstaltung-en","cat_veranstaltung-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/dam-online.de\/en\/wp-json\/wp\/v2\/tribe_events\/64887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dam-online.de\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/dam-online.de\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/dam-online.de\/en\/wp-json\/wp\/v2\/users\/7"}],"version-history":[{"count":0,"href":"https:\/\/dam-online.de\/en\/wp-json\/wp\/v2\/tribe_events\/64887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dam-online.de\/en\/wp-json\/wp\/v2\/media\/64882"}],"wp:attachment":[{"href":"https:\/\/dam-online.de\/en\/wp-json\/wp\/v2\/media?parent=64887"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dam-online.de\/en\/wp-json\/wp\/v2\/tags?post=64887"},{"taxonomy":"veranstaltungs_formate","embeddable":true,"href":"https:\/\/dam-online.de\/en\/wp-json\/wp\/v2\/veranstaltungs_formate?post=64887"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/dam-online.de\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=64887"},{"taxonomy":"hf_cat_tribe_events","embeddable":true,"href":"https:\/\/dam-online.de\/en\/wp-json\/wp\/v2\/hf_cat_tribe_events?post=64887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}